{"id":5864,"date":"2021-09-27T10:40:17","date_gmt":"2021-09-27T08:40:17","guid":{"rendered":"https:\/\/stiftadmont.at\/?page_id=5864"},"modified":"2026-07-07T11:00:10","modified_gmt":"2026-07-07T09:00:10","slug":"resena-de-la-exposicion","status":"publish","type":"page","link":"https:\/\/stiftadmont.at\/es\/museum\/ausstellungsrueckblick\/","title":{"rendered":"Rese\u00f1a de la exposici\u00f3n"},"content":{"rendered":"<section id='lightpress__section--block_718b2667bf8b04de99df126c7e77a4e7' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Gegenwartskunst_c-Thomas_Sattler_10_2-1024x768.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Gegenwartskunst_c-Thomas_Sattler_10_2-1024x768.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\"\n                                 src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Gegenwartskunst_c-Thomas_Sattler_10_2-1024x768.jpg\"\n                                 alt=\"Arte contempor\u00e1neo c Thomas Sattler\" width=\"600\" height=\"450\">\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Arte contempor\u00e1neo entre muros antiguos<\/h5>\n<h5 class=\"heading-m\">2024 \/ 2025<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">Esta exposici\u00f3n especial ofreci\u00f3 una visi\u00f3n representativa de la colecci\u00f3n m\u00e1s reciente de la Abad\u00eda de Admont. Est\u00e1 dedicada al arte contempor\u00e1neo y lleva en construcci\u00f3n desde 1997. Actualmente consta de m\u00e1s de 1.000 obras de unos 180 artistas austriacos, la mayor\u00eda nacidos en la segunda mitad del siglo XX.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"https:\/\/stiftadmont.at\/es\/exposiciones-actuales\/arte-contemporaneo-entre-muros-antiguos\/\" target=\"_blank\" rel=\"noopener\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_1998216c3efe323cc338764cb4900612' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Stift-Admont-GWK-Gustav-Zankl-\u00a9-Michael-Braunsteiner-1024x683.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Stift-Admont-GWK-Gustav-Zankl-\u00a9-Michael-Braunsteiner-1024x683.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Stift-Admont-GWK-Gustav-Zankl-\u00a9-Michael-Braunsteiner-1024x683.jpg\" alt=\"Abad\u00eda de Admont GWK Gustav Zankl \u00a9 Michael Braunsteiner\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Zankl se re\u00fane con Schwarz<\/h5>\n<h5 class=\"heading-m\">2024\/2025<\/h5>\n<p class=\"paragraph-m\">\u00a0<\/p>\n<p>En una secci\u00f3n del Museo de Arte Contempor\u00e1neo se hace tangible la evoluci\u00f3n de dos artistas importantes para la escena art\u00edstica de Estiria en la posguerra: Hannes Schwarz (1926 - 2014) y Gustav Zankl (*1929). El arte expresivo se encuentra con el arte concreto. Ambos artistas est\u00e1n unidos por una \u00e9tica del arte que promueve el pensamiento cr\u00edtico.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"https:\/\/stiftadmont.at\/es\/exposiciones-actuales\/zankl-se-reune-con-black-2025\/\">M\u00e1s informaci\u00f3n<\/a><\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"https:\/\/stiftadmont.at\/es\/proyecto-conmemorativo-contramundos\/\">Proyecto conmemorativo de Contramundos - Hannes Schwarz (1926-2014)<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_fdb363a881056ff76e6e41e7415b511a' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Kurt-Ryslavy-3_www-1024x768.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Kurt-Ryslavy-3_www-1024x768.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Kurt-Ryslavy-3_www-1024x768.jpg\" alt=\"Kurt Ryslavy 3 www\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Kurt Ryslavy<\/h5>\n<h5 class=\"heading-m\">2023<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">La exposici\u00f3n especial 2023 de Kurt Ryslavy en el Museo de Arte Contempor\u00e1neo de la Abad\u00eda de Admont mostr\u00f3 su pr\u00e1ctica art\u00edstica para plantear cuestiones sobre el valor (del arte) en t\u00e9rminos cualitativos y cuantitativos.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/museo-de-arte-contemporaneo-kurt-ryslavy\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_a072c5814ba865b925dd85bab7b06448' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Nikola-Irmer-White-Specola-Oel-auf-Leinen-2018-1024x836.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Nikola-Irmer-White-Specola-Oel-auf-Leinen-2018-1024x836.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Nikola-Irmer-White-Specola-Oel-auf-Leinen-2018-1024x836.jpg\" alt=\"Nikola Irmer White Specola \u00f3leo sobre lino 2018\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Obras de Nikola Irmer en el Museo de Historia Natural<\/h5>\n<h5 class=\"heading-m\">2022<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">En el Museo de Historia Natural de la Abad\u00eda de Admont, las obras de arte contempor\u00e1neo de Nikola Irmer dialogaron con los espec\u00edmenes hist\u00f3ricos all\u00ed expuestos y con la actual exposici\u00f3n especial del Museo de Arte Contempor\u00e1neo de 2022.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/admont-guests\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_32e1244396bdb55c9bc696bef402f1f7' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Friedl-677x1024_www.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Friedl-677x1024_www.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Friedl-677x1024_www.jpg\" alt=\"Friedl 677x1024 www\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Heribert Friedl - Intervenci\u00f3n art\u00edstica<\/h5>\n<h5 class=\"heading-m\">2022<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">Desde 2003, el Kunsthistorisches Museum cuenta con un espacio de intervenci\u00f3n art\u00edstica. Un espacio de relaciones resonantes, de di\u00e1logo: lo sagrado con lo profano, el pasado con el presente. Transformaciones y procesos. En 2022, esta sala fue dise\u00f1ada por Heribert Friedl.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/heribert-friedl-intervencion-artistica-2023\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<p>\u00a0<\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_0956b116eda2efca7033a931150ceaae' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Nikola-Irmer-Lemur-Oel-auf-Leinen-2016-1-1024x720.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Nikola-Irmer-Lemur-Oel-auf-Leinen-2016-1-1024x720.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Nikola-Irmer-Lemur-Oel-auf-Leinen-2016-1-1024x720.jpg\" alt=\"Nikola Irmer Lemur \u00f3leo sobre lino 2016 1\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 id=\"h_48261307724861632732924095\" class=\"heading-m line line-above line--gold\">Ra\u00edces estirias<\/h5>\n<h5 class=\"heading-m\">2022<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\"><span style=\"color: #777777; font-family: ibm_plex_sansregular, sans-serif; background-color: #ffffff;\">La exposici\u00f3n especial 2022 del Museo de Arte Contempor\u00e1neo de la Abad\u00eda de Admont mostrar\u00e1 obras de \"Ra\u00edces Estirias\". Cuando se cre\u00f3 la colecci\u00f3n de arte contempor\u00e1neo de la Abad\u00eda de Admont, se puso de manifiesto que muchos de los artistas representados en esta nueva parte de la colecci\u00f3n hab\u00edan nacido en Estiria o est\u00e1n arraigados en la regi\u00f3n de alguna otra manera.<\/span><\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button--secondary admont-button--header admont-button\" href=\"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/exposicion-especial-2022-raices-estirias\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_74c10a2b42b98021ce0a7d76e487597f' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Neue-Medien-2-1-1024x668.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Neue-Medien-2-1-1024x668.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\"\n                                 src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Neue-Medien-2-1-1024x668.jpg\"\n                                 alt=\"Nuevos medios 2 1 a escala\" width=\"600\" height=\"450\">\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 id=\"h_48261307724861632732924095\" class=\"heading-m line line-above line--gold\">Poder y \"nuevos medios de comunicaci\u00f3n\" en el umbral de la Edad Moderna<\/h5>\n<p>2022<\/p>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">A lo largo de su reinado, el emperador Maximiliano I encarg\u00f3 a importantes eruditos y artistas que informaran sobre sus hechos y donaciones con palabras e im\u00e1genes. Con ello pretend\u00eda asegurar su memoria, su \"Gedechtnus\", para la posteridad y servir de ejemplo a futuros pr\u00edncipes. Para ello utiliz\u00f3 nuevas t\u00e9cnicas y estrategias que se desarrollaron en el umbral de la Edad Moderna.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button--secondary admont-button--header admont-button\" href=\"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/poder-y-nuevos-medios-de-comunicacion\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<p>\u00a0<\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_4d29d32f7774bfcaee4e98f5fe357563' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Friedrich-und-Maximilian-2021@Sattler_5.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Friedrich-und-Maximilian-2021@Sattler_5.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Friedrich-und-Maximilian-2021@Sattler_5.jpg\" alt=\"Friedrich y Maximilian 2021@Sattler 5\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Exposici\u00f3n especial<\/h5>\n<h5 class=\"heading-m\">2022<\/h5>\n<p>\u00a0<\/p>\n<p><strong>NOSOTROS FRIEDRICH III &amp; MAXIMILIAN I - \u00a1Patrimonio cultural en movimiento!<br \/><\/strong><\/p>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">En la temporada del museo del a\u00f1o pasado, dos emperadores del periodo de transici\u00f3n de la Edad Media a la Edad Moderna hicieron su entrada - en las salas vecinas de la exposici\u00f3n g\u00f3tica permanente de la planta baja y extendida a la sala de manuscritos de la primera planta. Federico III y Maximiliano I de la Casa de Habsburgo - padre e hijo.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/wefriedrichymaximilian-la-cultura-se-mueve\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_dc67f1d22baa0bc4494d8af18388c93e' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Friedrich-und-Maximilian-2021_2-1024x669.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Friedrich-und-Maximilian-2021_2-1024x669.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Friedrich-und-Maximilian-2021_2-1024x669.jpg\" alt=\"Federico y Maximiliano 2021 2\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Exposici\u00f3n especial<\/h5>\n<h5 class=\"heading-m\">2021<\/h5>\n<p><strong><br \/>FRIEDRICH III Y MAXIMILIANO I - Su mundo y su \u00e9poca<\/strong><\/p>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">En el Museo G\u00f3tico ampliado, la abad\u00eda de Admont present\u00f3 una exposici\u00f3n especial sobre las dos personalidades de los Habsburgo, Federico III y su hijo Maximiliano I, en su entramado din\u00e1stico y su entorno. Este periodo abarcaba la transici\u00f3n de la Baja Edad Media con el G\u00f3tico tard\u00edo al Renacimiento. M\u00e1s de 200 piezas procedentes de 46 prestadores le garantizaron un encuentro intenso y expresivo.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/exposicion-especial-friedrich\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<p>\u00a0<\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_a2b07022f13d29d4725ae1164f3f81f2' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/MZ20-Verortungen-Insekten-Huber178-1024x683.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/MZ20-Verortungen-Insekten-Huber178-1024x683.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\"\n                                 src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/MZ20-Verortungen-Insekten-Huber178-1024x683.jpg\"\n                                 alt=\"MZ20 Ubicaciones Insectos Huber178 a escala\" width=\"600\" height=\"450\">\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 id=\"h_48261307724861632732924095\" class=\"heading-m line line-above line--gold\">Insectos<\/h5>\n<h5 class=\"heading-m\">2020<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\"><span style=\"color: #777777; font-family: ibm_plex_sansregular, sans-serif;\"><span style=\"background-color: #ffffff;\">En la temporada 2020, la Sala de Intervenciones Art\u00edsticas del Kunsthistorisches Museum se decorar\u00e1 con recortes de papel sobre el tema \"Insectos\" de la artista Lisa Huber. A Huber no le interesa la cercan\u00eda naturalista en la representaci\u00f3n, sino m\u00e1s bien la abstracci\u00f3n, la esquematizaci\u00f3n y, no menos importante, la ornamentalizaci\u00f3n, siguiendo los modelos hist\u00f3ricos.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button--secondary admont-button--header admont-button\" href=\"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/insectos\/\" target=\"_blank\" rel=\"noopener\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<p>\u00a0<\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_0fd081755a010727ddb6c507ecd50bd4' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/MZ20-Verortungen-189-1-1024x683.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/MZ20-Verortungen-189-1-1024x683.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\"\n                                 src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/MZ20-Verortungen-189-1-1024x683.jpg\"\n                                 alt=\"MZ20 Localizaciones 189 1 a escala\" width=\"600\" height=\"450\">\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Localizaciones - MADE FOR ADMONT #fotografie<\/h5>\n<h5 class=\"heading-m\">2020<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">La exposici\u00f3n especial 2021 representa el amplio espectro de fotograf\u00edas MADE FOR ADMONT con una selecci\u00f3n de la propia colecci\u00f3n del monasterio. Las obras expuestas son el resultado de procesos de localizaci\u00f3n espec\u00edficos relacionados con la regi\u00f3n, el monasterio y las personas que trabajan en \u00e9l, el museo y sus contenidos.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"https:\/\/stiftadmont.at\/es\/museo\/sonderausstellung\/verortungen-made-for-admont\/\" target=\"_blank\" rel=\"noopener\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_5ad2bba1bf430d219cad5e531e8535ec' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/WALDEN_1.5.1-1024x429.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/WALDEN_1.5.1-1024x429.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/WALDEN_1.5.1-1024x429.jpg\" alt=\"WALDEN 1.5.1\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Walden<\/h5>\n<h5 class=\"heading-m\">2019<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">En el bosque mon\u00e1stico de la abad\u00eda de Admont, se tal\u00f3 un abeto y se transform\u00f3 en 1.500 tablillas de madera, que se apilaron y transportaron en tren, cami\u00f3n y barco hasta la selva brasile\u00f1a. WALDEN retrata el parad\u00f3jico viaje de la pila de listones de madera a lo largo de las rutas comerciales globalizadas hasta su misterioso destino final, Campinha, en el curso medio del R\u00edo Negro, cerca de una comunidad ind\u00edgena en medio del Amazonas, utilizando escenas de 360\u00b0 llenas de tiempo.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"\/es\/museo\/resena-de-la-exposicion\/walden\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_7465e8900380cf70f139c0868ff9d736' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/ea1a5f9bdcefc9d101924fc9b969b528_XL-1024x768.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/ea1a5f9bdcefc9d101924fc9b969b528_XL-1024x768.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/ea1a5f9bdcefc9d101924fc9b969b528_XL-1024x768.jpg\" alt=\"Play Art- Arte para todos 2021\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Jugar al arte<\/h5>\n<h5 class=\"heading-m\">2019<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">Como aproximaci\u00f3n a este tema especial, los artistas abordan el hecho de ser ciego o discapacitado visual de diferentes maneras. Las obras pr\u00e1cticas ofrecen a invidentes y videntes el mismo acceso al arte contempor\u00e1neo.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"\/es\/museo\/resena-de-la-exposicion\/arte-ludico-arte-para-todos\/\" target=\"_blank\" rel=\"noopener\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_f71c3ac23220574ee9aae877cb0c55e2' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Abrogans1a-e1632831894693-1024x768.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Abrogans1a-e1632831894693-1024x768.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Abrogans1a-e1632831894693-1024x768.jpg\" alt=\"De abroganos y Nibelungos 2021\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">De abroganos y nibelungos<\/h5>\n<h5 class=\"heading-m\">2018<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">Los monasterios son verdaderos tesoros cuando se trata de documentos antiguos. Una y otra vez se encuentran en sus archivos documentos legendarios. La exposici\u00f3n muestra hallazgos sensacionales procedentes de nueve monasterios austriacos.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"\/es\/museo\/resena-de-la-exposicion\/de-abroganos-y-nibelungos\/\" target=\"_blank\" rel=\"noopener\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_442c109f2f29fce702a581f00defa373' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Admont-Blick-in-die-Ausstellung-Schnheit-und-Anspruch-1024x640.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Admont-Blick-in-die-Ausstellung-Schnheit-und-Anspruch-1024x640.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\"\n                                 src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Admont-Blick-in-die-Ausstellung-Schnheit-und-Anspruch-1024x640.jpg\"\n                                 alt=\"Admont Vista de la exposici\u00f3n Belleza y aspiraci\u00f3n a escala e1632930949300\" width=\"600\" height=\"450\">\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Belleza y aspiraci\u00f3n<\/h5>\n<h5 class=\"heading-m\">2017<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">Con el Museo de Arte Contempor\u00e1neo de la Abad\u00eda de Admont y la Casa de Arte Contempor\u00e1neo de la Di\u00f3cesis de Graz-Seckau, Estiria no tiene rival en Europa en cuanto a densidad de arte contempor\u00e1neo en el contexto de la iglesia. M\u00e1s de 50 obras ofrecen una visi\u00f3n de las distintas colecciones.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"\/es\/museo\/resena-de-la-exposicion\/belleza-y-aspiracion\/\" target=\"_blank\" rel=\"noopener\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_1b39f772943016c309673547d41c0898' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/6ef598b10d1539793d4ace8d8b7b613f_XL-1024x768.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/6ef598b10d1539793d4ace8d8b7b613f_XL-1024x768.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/6ef598b10d1539793d4ace8d8b7b613f_XL-1024x768.jpg\" alt=\"6ef598b10d1539793d4ace8d8b7b613f XL\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">ABRE EL ENLACE.<\/h5>\n<h5 class=\"heading-m\">2017<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">La Abad\u00eda de Admont colecciona arte contempor\u00e1neo desde 1997. En la colecci\u00f3n est\u00e1n representadas adquisiciones y encargos de arte de unos 170 artistas austriacos. ABRA EL V\u00cdNCULO. ofrece una visi\u00f3n del crecimiento de la colecci\u00f3n y de las propias obras.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"\/es\/museo\/resena-de-la-exposicion\/abrir-el-enlace\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_daab4306948b9c8f2ac044c4d0ff574c' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Kuenstlerische_Intervention_2017Marcel_Peda_2-1024x768.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Kuenstlerische_Intervention_2017Marcel_Peda_2-1024x768.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Kuenstlerische_Intervention_2017Marcel_Peda_2-1024x768.jpg\" alt=\"Intervenci\u00f3n art\u00edstica 2017Marcel Peda 2\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">SkyHellDress<\/h5>\n<h5 class=\"heading-m\">2017<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">El espacio de intervenci\u00f3n art\u00edstica ser\u00e1 dise\u00f1ado por Carola Willbrand en 2017. Una casulla en forma de campana cosida con papel textil hecho a mano ocupa el espacio.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"\/es\/museo\/resena-de-la-exposicion\/himelshoellenkleid\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_27b36fcd677caa657c97c19b6fdaa82c' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/037_Stift-Admont_\u00a9StefanLeitner_LEI7338-e1634720409732-1024x768.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/037_Stift-Admont_\u00a9StefanLeitner_LEI7338-e1634720409732-1024x768.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/037_Stift-Admont_\u00a9StefanLeitner_LEI7338-e1634720409732-1024x768.jpg\" alt=\"037 Abad\u00eda de Admont \u00a9StefanLeitner LEI7338 e1634720409732\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">NEO\/NEW - Redescubierto en el Kunsthistorisches Museum<\/h5>\n<h5 class=\"heading-m\">2017<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">Inspir\u00e1ndose en la singular exposici\u00f3n g\u00f3tica, el Kunsthistorisches Museum Admont tambi\u00e9n muestra algunas rarezas especiales en la temporada 2017 y 2018<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"\/es\/museo\/resena-de-la-exposicion\/neo-redescubierto-en-el-museo-de-historia-del-arte\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_769f3eb12272caf0c1a69dd978e4c6dc' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/handschrift-1024x667.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/handschrift-1024x667.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/handschrift-1024x667.jpg\" alt=\"Exposici\u00f3n de manuscritos 2017\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Exposici\u00f3n de manuscritos 2017<\/h5>\n<h5 class=\"heading-m\">2017<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">Una mirada retrospectiva a la exposici\u00f3n de manuscritos de 2017: De los 1000 manuscritos medievales conservados en la abad\u00eda benedictina de Admont, algunos de los cuales fueron creados aqu\u00ed, la mayor\u00eda datan del periodo g\u00f3tico.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"\/es\/museo\/resena-de-la-exposicion\/exposicion-de-manuscritos-2017\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_20edcae7b4db42e49257497e3e5108b6' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/nhm-1024x684.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/nhm-1024x684.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/nhm-1024x684.jpg\" alt=\"Un placer comer 2021\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">Comer con placer<\/h5>\n<h5 class=\"heading-m\">2016<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">Los \"ratones de biblioteca\" que trabajan en la Biblioteca de la Abad\u00eda sirven de inspiraci\u00f3n para esta polifac\u00e9tica exposici\u00f3n especial. Los distintos espacios del museo abordan el tema de la \"alimentaci\u00f3n\" desde diferentes \u00e1ngulos, desde representaciones de cocina hasta manuscritos sobre ganader\u00eda.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"\/es\/museo\/resena-de-la-exposicion\/para-comer\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>\n\n<section id='lightpress__section--block_00b5731bd278e942090663d0db82fb10' class='lightpress__section--default-section-space lightpress__section lightpress__section--content'><div class=\"content__inner\"\n         x-init=\"initContentBlockAnim($el)\">\n        \n    <div class=\"content__grid content__grid--fifty-fifty\">\n                                            <div class=\"content__box content__box\"\n                 style=\"\">\n                                \n                \n                                        <div class=\"content__media stickyTo\" x-init=\"imageSticky($el)\">\n\n                                                                                                <picture\n                                class=\"content__image sticky\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/feuer-1024x690.jpg\"\n                                    type=\"image\/webp\">\n                            <source srcset=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/feuer-1024x690.jpg\"\n                                    type=\"image\/jpeg\">\n                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/feuer-1024x690.jpg\" alt=\"Fuego: una maldici\u00f3n y una bendici\u00f3n 2021\" width=\"600\" height=\"450\" \/>\n                                                                                                            <\/picture>\n\n                    <\/div>\n\n                            <\/div>\n        \n                                                    <div class=\"content__box content__box--2\"\n                     >\n                                        \n                    \n                                                    <div class=\"prose\"><h5 class=\"heading-m line line-above line--gold\">El fuego, maldici\u00f3n y bendici\u00f3n a la vez<\/h5>\n<h5 class=\"heading-m\">2015<\/h5>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">El fuego ha fascinado a la humanidad desde que tenemos memoria. Proporciona calor y luz. Con \u00e9l se preparan alimentos, se ahuyenta a los animales salvajes y se transforman los metales en espadas o rejas de arado.<\/p>\n<p>\u00a0<\/p>\n<p class=\"paragraph-m\">Al mismo tiempo, la gente vive el fuego como una amenaza. Pueblos y ciudades, bosques y campos arden hasta los cimientos. El fuego sirve de arma y destruye la vida. Las hogueras del infierno arden tanto como las piras de las brujas.<\/p>\n<p>\u00a0<\/p>\n<p><a class=\"admont-button admont-button--secondary\" href=\"\/es\/museo\/resena-de-la-exposicion\/el-fuego-es-a-la-vez-una-maldicion-y-una-bendicion\/\">M\u00e1s informaci\u00f3n sobre la exposici\u00f3n<\/a><\/p>\n<\/div>\n                        \n                                    <\/div>\n            \n            <\/div>\n<\/div>\n\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":457,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"class_list":["post-5864","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ausstellungsr\u00fcckblick - Stift Admont<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ausstellungsr\u00fcckblick\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/\" \/>\n<meta property=\"og:site_name\" content=\"Stift Admont\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T09:00:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stiftadmont.at\/wp-content\/uploads\/Klosteranlage-innen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1912\" \/>\n\t<meta property=\"og:image:height\" content=\"1188\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stiftadmont.at\\\/museum\\\/ausstellungsrueckblick\\\/\",\"url\":\"https:\\\/\\\/stiftadmont.at\\\/museum\\\/ausstellungsrueckblick\\\/\",\"name\":\"Ausstellungsr\u00fcckblick - Stift Admont\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftadmont.at\\\/#website\"},\"datePublished\":\"2021-09-27T08:40:17+00:00\",\"dateModified\":\"2026-07-07T09:00:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stiftadmont.at\\\/museum\\\/ausstellungsrueckblick\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stiftadmont.at\\\/museum\\\/ausstellungsrueckblick\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stiftadmont.at\\\/museum\\\/ausstellungsrueckblick\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/stiftadmont.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museum Stift Admont\",\"item\":\"https:\\\/\\\/stiftadmont.at\\\/museum\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ausstellungsr\u00fcckblick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stiftadmont.at\\\/#website\",\"url\":\"https:\\\/\\\/stiftadmont.at\\\/\",\"name\":\"Stift Admont\",\"description\":\"Benediktinerkloster und Sehensw\u00fcrdigkeit im Ges\u00e4use\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stiftadmont.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rese\u00f1a de la exposici\u00f3n - Admont Abbey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/","og_locale":"es_ES","og_type":"article","og_title":"Ausstellungsr\u00fcckblick","og_url":"https:\/\/stiftadmont.at\/es\/museo\/resena-de-la-exposicion\/","og_site_name":"Stift Admont","article_modified_time":"2026-07-07T09:00:10+00:00","og_image":[{"width":1912,"height":1188,"url":"https:\/\/stiftadmont.at\/wp-content\/uploads\/Klosteranlage-innen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stiftadmont.at\/museum\/ausstellungsrueckblick\/","url":"https:\/\/stiftadmont.at\/museum\/ausstellungsrueckblick\/","name":"Rese\u00f1a de la exposici\u00f3n - Admont Abbey","isPartOf":{"@id":"https:\/\/stiftadmont.at\/#website"},"datePublished":"2021-09-27T08:40:17+00:00","dateModified":"2026-07-07T09:00:10+00:00","breadcrumb":{"@id":"https:\/\/stiftadmont.at\/museum\/ausstellungsrueckblick\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stiftadmont.at\/museum\/ausstellungsrueckblick\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stiftadmont.at\/museum\/ausstellungsrueckblick\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/stiftadmont.at\/"},{"@type":"ListItem","position":2,"name":"Museum Stift Admont","item":"https:\/\/stiftadmont.at\/museum\/"},{"@type":"ListItem","position":3,"name":"Ausstellungsr\u00fcckblick"}]},{"@type":"WebSite","@id":"https:\/\/stiftadmont.at\/#website","url":"https:\/\/stiftadmont.at\/","name":"Abad\u00eda de Admont","description":"Monasterio benedictino y atracci\u00f3n tur\u00edstica en el Ges\u00e4use","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stiftadmont.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/stiftadmont.at\/es\/wp-json\/wp\/v2\/pages\/5864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stiftadmont.at\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stiftadmont.at\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stiftadmont.at\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/stiftadmont.at\/es\/wp-json\/wp\/v2\/comments?post=5864"}],"version-history":[{"count":175,"href":"https:\/\/stiftadmont.at\/es\/wp-json\/wp\/v2\/pages\/5864\/revisions"}],"predecessor-version":[{"id":42063,"href":"https:\/\/stiftadmont.at\/es\/wp-json\/wp\/v2\/pages\/5864\/revisions\/42063"}],"up":[{"embeddable":true,"href":"https:\/\/stiftadmont.at\/es\/wp-json\/wp\/v2\/pages\/457"}],"wp:attachment":[{"href":"https:\/\/stiftadmont.at\/es\/wp-json\/wp\/v2\/media?parent=5864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stiftadmont.at\/es\/wp-json\/wp\/v2\/categories?post=5864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}